{"id":24462,"date":"2026-07-08T12:12:26","date_gmt":"2026-07-08T16:12:26","guid":{"rendered":"https:\/\/plq.org\/?p=24462"},"modified":"2026-07-08T12:12:26","modified_gmt":"2026-07-08T16:12:26","slug":"caroline-de-guire-candidate-officielle-du-parti-liberal-du-quebec-dans-laval-des-rapides","status":"publish","type":"post","link":"https:\/\/plq.org\/en\/caroline-de-guire-candidate-officielle-du-parti-liberal-du-quebec-dans-laval-des-rapides\/","title":{"rendered":"Caroline De Guire, candidate officielle du Parti lib\u00e9ral du Qu\u00e9bec dans Laval-des-Rapides"},"content":{"rendered":"<p class=\"font-claude-response-body break-words whitespace-normal\">Laval, le 7 juillet 2026 \u2014 C&rsquo;est en pr\u00e9sence du chef du Parti lib\u00e9ral du Qu\u00e9bec, Charles Milliard, et de militants de la r\u00e9gion que Mme Caroline De Guire a \u00e9t\u00e9 officiellement annonc\u00e9e comme candidate du Parti lib\u00e9ral du Qu\u00e9bec dans la circonscription de Laval-des-Rapides en vue des prochaines \u00e9lections g\u00e9n\u00e9rales.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\u00c9conomiste de formation et gestionnaire reconnue, Caroline De Guire cumule plus de 25 ans d&rsquo;exp\u00e9rience en d\u00e9veloppement \u00e9conomique, en entrepreneuriat, en innovation et en repr\u00e9sentation des milieux d&rsquo;affaires. Titulaire d&rsquo;une ma\u00eetrise en sciences \u00e9conomiques de l&rsquo;Universit\u00e9 de Montr\u00e9al, elle a consacr\u00e9 sa carri\u00e8re \u00e0 rassembler les entreprises, les institutions et les partenaires du milieu autour de projets qui contribuent \u00e0 la croissance et au d\u00e9veloppement des communaut\u00e9s.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Depuis 2020, elle dirige la Chambre de commerce et d&rsquo;industrie de Laval, l&rsquo;une des plus importantes chambres de commerce au Qu\u00e9bec. Sous sa direction, l&rsquo;organisation a renforc\u00e9 son r\u00f4le comme acteur incontournable du d\u00e9veloppement \u00e9conomique r\u00e9gional, en faisant avancer plusieurs dossiers li\u00e9s notamment \u00e0 la productivit\u00e9, au d\u00e9veloppement durable, \u00e0 l&rsquo;achat local, \u00e0 la rel\u00e8ve entrepreneuriale, \u00e0 la francisation et \u00e0 l&rsquo;innovation.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Reconnue pour sa capacit\u00e9 \u00e0 mobiliser, \u00e0 b\u00e2tir des ponts et \u00e0 transformer les id\u00e9es en actions concr\u00e8tes, Caroline De Guire a travaill\u00e9 en \u00e9troite collaboration avec les entrepreneurs, les institutions publiques, les \u00e9lus municipaux et les organismes communautaires afin de trouver des solutions aux d\u00e9fis \u00e9conomiques et sociaux de la r\u00e9gion. Son parcours t\u00e9moigne d&rsquo;une volont\u00e9 constante de rassembler les acteurs du milieu autour d&rsquo;objectifs communs.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Une personne de terrain profond\u00e9ment attach\u00e9e au d\u00e9veloppement de Laval, elle souhaite aujourd&rsquo;hui mettre son exp\u00e9rience au service des citoyens de Laval-des-Rapides. Convaincue que la prosp\u00e9rit\u00e9 \u00e9conomique est essentielle pour am\u00e9liorer la qualit\u00e9 de vie des Qu\u00e9b\u00e9cois et renforcer nos services publics, Caroline De Guire souhaite contribuer \u00e0 b\u00e2tir un Qu\u00e9bec plus efficace, plus ambitieux et plus humain.<\/p>\n<blockquote>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\u00ab Depuis plus de 25 ans, j&rsquo;ai le privil\u00e8ge de travailler avec des entrepreneurs, des organisations et des citoyens qui font avancer nos communaut\u00e9s. Laval est une ville d&rsquo;innovation, d&rsquo;ambition et de possibilit\u00e9s. Aujourd&rsquo;hui, je souhaite mettre cette exp\u00e9rience au service des citoyens de Laval-des-Rapides afin de continuer \u00e0 b\u00e2tir des ponts et trouver des solutions concr\u00e8tes aux d\u00e9fis auxquels nous faisons face. Je suis tr\u00e8s fi\u00e8re de me joindre \u00e0 l&rsquo;\u00e9quipe de Charles Milliard, une \u00e9quipe qui veut remettre l&rsquo;\u00e9conomie, les r\u00e9gions et les citoyens au c\u0153ur de nos d\u00e9cisions. \u00bb<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\u2014 Caroline De Guire, candidate du PLQ dans Laval-des-Rapides<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\u00ab Caroline De Guire est une personne d&rsquo;action qui a consacr\u00e9 sa carri\u00e8re \u00e0 faire avancer Laval et \u00e0 accompagner ceux qui cr\u00e9ent de la richesse dans nos communaut\u00e9s. Elle comprend les r\u00e9alit\u00e9s des entrepreneurs, l&rsquo;importance de l&rsquo;innovation et la n\u00e9cessit\u00e9 de b\u00e2tir une \u00e9conomie forte pour se donner les moyens de nos ambitions. Avec son exp\u00e9rience, son leadership et sa connaissance du terrain, Caroline sera une voix forte pour les citoyens de Laval-des-Rapides et un ajout important \u00e0 notre \u00e9quipe. \u00bb<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">\u2014 Charles Milliard, chef du Parti lib\u00e9ral du Qu\u00e9bec<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Laval, le 7 juillet 2026 \u2014 C&rsquo;est en pr\u00e9sence du chef du Parti lib\u00e9ral du Qu\u00e9bec, Charles Milliard, et de militants de la r\u00e9gion que Mme Caroline De Guire a&#8230;<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"inline_featured_image":false,"footnotes":""},"categories":[170],"tags":[],"circonscription":[68],"dossier":[175],"langue":[173,174],"nouvelle-a-la-une":[],"class_list":{"0":"post-24462","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-communique","7":"circonscription-laval-des-rapides","8":"dossier-le-parti","9":"langue-francais","10":"langue-anglais"},"acf":[],"_links":{"self":[{"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/posts\/24462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/comments?post=24462"}],"version-history":[{"count":1,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/posts\/24462\/revisions"}],"predecessor-version":[{"id":24463,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/posts\/24462\/revisions\/24463"}],"wp:attachment":[{"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/media?parent=24462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/categories?post=24462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/tags?post=24462"},{"taxonomy":"circonscription","embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/circonscription?post=24462"},{"taxonomy":"dossier","embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/dossier?post=24462"},{"taxonomy":"langue","embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/langue?post=24462"},{"taxonomy":"nouvelle-a-la-une","embeddable":true,"href":"https:\/\/plq.org\/en\/wp-json\/wp\/v2\/nouvelle-a-la-une?post=24462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}